{"id":13591,"date":"2024-04-17T17:44:29","date_gmt":"2024-04-17T15:44:29","guid":{"rendered":"https:\/\/nexvision.dev\/votre-besoin\/"},"modified":"2024-09-26T15:53:17","modified_gmt":"2024-09-26T13:53:17","slug":"votre-besoin","status":"publish","type":"page","link":"https:\/\/nexvision.fr\/fr\/votre-besoin\/","title":{"rendered":"Votre besoin"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13591\" class=\"elementor elementor-13591 elementor-12832\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-2c74451 elementor-section-height-min-height elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"2c74451\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-310748a\" data-id=\"310748a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06904b4 elementor-widget elementor-widget-heading\" data-id=\"06904b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Votre besoin<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-592321e elementor-widget elementor-widget-text-editor\" data-id=\"592321e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Concevoir un syst\u00e8me optronique<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-c6bbf14 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c6bbf14\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-963f9c7\" data-id=\"963f9c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a51495e elementor-widget elementor-widget-heading\" data-id=\"a51495e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prototyper un syst\u00e8me de vision complet : calculateur + capteurs (vision, radar, lidar\u2026)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d73509c elementor-widget elementor-widget-text-editor\" data-id=\"d73509c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Vous avez besoin de concevoir un syst\u00e8me embarqu\u00e9 complet qui r\u00e9sout votre probl\u00e9matique (d\u00e9tecter, reconna\u00eetre, identifier, d\u00e9clencher une action&#8230;) ?<br \/>\n<\/strong> Nous d\u00e9risquons votre projet et concevons un syst\u00e8me incluant calculateur haute performance \u00e0 base de r\u00e9seaux de neurones (CPU\/GPU\/NPU\/FPGA : Nvidia AGX orin, Xilinx Ultrascale+\/Versal) et fusion multi-capteurs [cam\u00e9ras (UV, visible, nuit\/VNIR, SWIR, Thermique MWIR &amp; LWIR, THz), radar, lidar].<\/p>\n<ul>\n<li><a href=\"https:\/\/nexvision.fr\/fr\/expertise\/\">Notre expertise<\/a><\/li>\n<li><a href=\"https:\/\/nexvision.fr\/fr\/base-de-connaissances-sur-les-systemes-de-vision\/comprendre-le-fonctionnement-et-le-potentiel-des-systemes-optroniques\/part-4-votre-projet\/\">Questions \u00e0 vous poser<\/a>\u00a0si vous avez un projet de vision<\/li>\n<\/ul>\n<p><span style=\"text-decoration: underline;\">Notre exp\u00e9rience<\/span> : spatial, d\u00e9fense, a\u00e9ronautique, industrie, agriculture.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-07630ce\" data-id=\"07630ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bc5230 elementor-widget elementor-widget-image\" data-id=\"2bc5230\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nexvision.fr\/fr\/produits\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"566\" src=\"https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/03\/Ecosysteme-VPU_Mars2024-1024x724.png\" class=\"attachment-large size-large wp-image-11841\" alt=\"\" srcset=\"https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/03\/Ecosysteme-VPU_Mars2024-1024x724.png 1024w, https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/03\/Ecosysteme-VPU_Mars2024-300x212.png 300w, https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/03\/Ecosysteme-VPU_Mars2024-768x543.png 768w, https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/03\/Ecosysteme-VPU_Mars2024.png 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-42a1eaf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"42a1eaf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-68b7716\" data-id=\"68b7716\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81989b7 elementor-widget elementor-widget-image\" data-id=\"81989b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nexvision.fr\/fr\/produits\/evpu-calculateur-de-vision-embarque\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1524\" height=\"1003\" src=\"https:\/\/nexvision.fr\/wp-content\/uploads\/2023\/03\/eVPU_kaki.png\" class=\"attachment-full size-full wp-image-10946\" alt=\"\" srcset=\"https:\/\/nexvision.fr\/wp-content\/uploads\/2023\/03\/eVPU_kaki.png 1524w, https:\/\/nexvision.fr\/wp-content\/uploads\/2023\/03\/eVPU_kaki-300x197.png 300w, https:\/\/nexvision.fr\/wp-content\/uploads\/2023\/03\/eVPU_kaki-1024x674.png 1024w, https:\/\/nexvision.fr\/wp-content\/uploads\/2023\/03\/eVPU_kaki-768x505.png 768w\" sizes=\"(max-width: 1524px) 100vw, 1524px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3e4c8cc\" data-id=\"3e4c8cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ffb60b0 elementor-widget elementor-widget-heading\" data-id=\"ffb60b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cr\u00e9er un calculateur de vision embarqu\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-caa3721 elementor-widget elementor-widget-text-editor\" data-id=\"caa3721\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Vous disposez d\u00e9j\u00e0 d&rsquo;un syst\u00e8me de capteurs mais avez besoin d&rsquo;un calculateur embarqu\u00e9 puissant pour r\u00e9aliser le traitement et l&rsquo;analyse d&rsquo;images ?<\/strong><\/p>\n<p>Nous concevons votre calculateur haute performance sur mesure \u00e0 base de r\u00e9seaux de neurones (CPU\/GPU\/NPU\/FPGA : Nvidia AGX orin, Xilinx Ultrascale+\/Versal) selon vos contraintes SWaP-C pour qu&rsquo;il s&rsquo;int\u00e8gre parfaitement dans votre syst\u00e8me.<\/p>\n<p><span style=\"text-decoration: underline;\">Notre exp\u00e9rience<\/span> : spatial, d\u00e9fense, a\u00e9ronautique, industrie, agriculture.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-cd70d2f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cd70d2f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-97103f8\" data-id=\"97103f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22e5e4f elementor-widget elementor-widget-heading\" data-id=\"22e5e4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Concevoir un kit d'\u00e9valuation ou un reference design pour un capteur ou un processeur<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9eaac1 elementor-widget elementor-widget-text-editor\" data-id=\"b9eaac1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Vous \u00eates un fabricant de capteur d&rsquo;images ou de processeur ?<\/strong><\/p>\n<p>Nous concevons un kit d&rsquo;\u00e9valuation de votre processeur ou un reference design pour permettre \u00e0 des clients potentiels de tester votre device.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-67d2c9f\" data-id=\"67d2c9f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-295f8be elementor-widget elementor-widget-image\" data-id=\"295f8be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nexvision.fr\/fr\/reference-design-modules-electroniques-optionnels\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2397\" height=\"1724\" src=\"https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/05\/ISB_CMV_8000_nikon.png\" class=\"attachment-full size-full wp-image-13415\" alt=\"\" srcset=\"https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/05\/ISB_CMV_8000_nikon.png 2397w, https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/05\/ISB_CMV_8000_nikon-300x216.png 300w, https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/05\/ISB_CMV_8000_nikon-1024x736.png 1024w, https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/05\/ISB_CMV_8000_nikon-768x552.png 768w, https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/05\/ISB_CMV_8000_nikon-1536x1105.png 1536w, https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/05\/ISB_CMV_8000_nikon-2048x1473.png 2048w\" sizes=\"(max-width: 2397px) 100vw, 2397px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-cbeefb1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cbeefb1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3c01898\" data-id=\"3c01898\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de73ad1 elementor-widget elementor-widget-image\" data-id=\"de73ad1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/03\/IPCoreFPGA.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"IPCoreFPGA\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI1MDIsInVybCI6Imh0dHBzOlwvXC9uZXh2aXNpb24uZnJcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAzXC9JUENvcmVGUEdBLmpwZyJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1150\" height=\"661\" src=\"https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/03\/IPCoreFPGA.jpg\" class=\"attachment-full size-full wp-image-12502\" alt=\"\" srcset=\"https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/03\/IPCoreFPGA.jpg 1150w, https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/03\/IPCoreFPGA-300x172.jpg 300w, https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/03\/IPCoreFPGA-1024x589.jpg 1024w, https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/03\/IPCoreFPGA-768x441.jpg 768w\" sizes=\"(max-width: 1150px) 100vw, 1150px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f003be7\" data-id=\"f003be7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04cd47e elementor-widget elementor-widget-heading\" data-id=\"04cd47e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Acheter une IP<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7666f6 elementor-widget elementor-widget-text-editor\" data-id=\"a7666f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous recherchez une IP concernant le traitement ou l&rsquo;analyse d&rsquo;images ?<\/p>\n<p>Vous avez besoin de porter un algorithme de traitement ou d&rsquo;analyse d&rsquo;images sur un FPGA ou sur une autre architecture de traitement (CPU\/GPU\/Many core \/NPU\/DLA), nous le concevons et l&rsquo;impl\u00e9mentons pour vous.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-01a9c8f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"01a9c8f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ce43866\" data-id=\"ce43866\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-aa12dec\" data-id=\"aa12dec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09d002d elementor-widget elementor-widget-eael-feature-list\" data-id=\"09d002d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-feature-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"-icon-position-left -tablet-icon-position-left -mobile-icon-position-left\">\n\t\t\t<ul id=\"eael-feature-list-09d002d\" class=\"eael-feature-list-items circle stacked  eael-feature-list-vertical\" data-layout-tablet=\"vertical\" data-layout-mobile=\"vertical\">\n\t\t\t                <li class=\"eael-feature-list-item elementor-repeater-item-980f126\">\n                    \n\t\t\t\t\t\t<div class=\"eael-feature-list-icon-box\">\n\t\t\t\t\t\t\t<div class=\"eael-feature-list-icon-inner\">\n\n\t\t\t\t\t\t\t\t<span class=\"eael-feature-list-icon fl-icon-0\">\n\n\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"eael-feature-list-content-box\">\n                            <h2 class=\"eael-feature-list-title\">COMMENT POUVONS-NOUS VOUS AIDER ?<\/h2>\t\t\t\t\t\t<p class=\"eael-feature-list-content\"><\/p>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe356eb elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"fe356eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Suivant&quot;,&quot;step_previous_label&quot;:&quot;Pr\\u00e9c\\u00e9dent&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"13591\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"fe356eb\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Comment identifier vos besoins pour votre projet optronique ?\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"13591\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-step elementor-field-group elementor-column elementor-field-group-field_95daf42 elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"e-field-step elementor-hidden\" data-label=\"\" data-previousButton=\"\" data-nextButton=\"\" data-iconUrl=\"\" data-iconLibrary=\"fas fa-star\" data-icon=\"\" ><\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"6\" placeholder=\"Votre message\" required=\"required\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-step elementor-field-group elementor-column elementor-field-group-field_125925c elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"e-field-step elementor-hidden\" data-label=\"\" data-previousButton=\"Pr\u00e9c\u00e9dent\" data-nextButton=\"Suivant\" data-iconUrl=\"\" data-iconLibrary=\"fas fa-star\" data-icon=\"\" ><\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_83ba6e4 elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_83ba6e4]\" id=\"form-field-field_83ba6e4\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Votre entreprise\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Votre nom\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Votre email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_57342e6 elementor-col-100 recaptcha_v3-bottomright\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_57342e6\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LfGWysqAAAAADM9vMB0I4N4w_kwLPKI0Ntg-7xT\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomright\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Envoyer<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-85fb5bb\" data-id=\"85fb5bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-cb52757 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"cb52757\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bcc7bf8\" data-id=\"bcc7bf8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6adfd43 elementor-widget elementor-widget-heading\" data-id=\"6adfd43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">EXPERTISE OPTRONIQUE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5ec344 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-left elementor-widget elementor-widget-divider\" data-id=\"f5ec344\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<span class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tConception de syst\u00e8mes de vision embarqu\u00e9s\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ecf40ee elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ecf40ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Capteurs (visible, nuit\/VNIR, SWIR, Thermique MWIR\/LWIR) + LiDaR\/RaDaR 3D<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Electronique embarqu\u00e9e HPC (CPU\/GPU\/NPU\/FPGA)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Traitement et analyse d'images<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Interface utilisateur en r\u00e9alit\u00e9 mixte<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Firmware \/ Linux embarqu\u00e9<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fusion de donn\u00e9es<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Liens analogiques complexes et num\u00e9riques haut d\u00e9bit<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff1567c elementor-align-left elementor-widget elementor-widget-button\" data-id=\"ff1567c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/nexvision.fr\/fr\/expertise\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ENTRER<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f3cbc5c\" data-id=\"f3cbc5c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd3dbfe elementor-widget elementor-widget-heading\" data-id=\"fd3dbfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PRODUITS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3212df elementor-widget-divider--view-line_text elementor-widget-divider--element-align-left elementor-widget elementor-widget-divider\" data-id=\"f3212df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<span class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tUn \u00e9cosyst\u00e8me complet pour le situational awareness\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89a8f10 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"89a8f10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Unit\u00e9 de traitement<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cam\u00e9ras (visible, nuit\/VNIR, SWIR, Thermique MWIR\/LWIR)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Optroniques gyrostabilis\u00e9es<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lidar<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Projecteur de recherche<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">HMI<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Autre<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b425ef9 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"b425ef9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/nexvision.fr\/fr\/produits\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ENTRER<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-ba9f9fb elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba9f9fb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2488b9a\" data-id=\"2488b9a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-afb7da6 elementor-widget elementor-widget-heading\" data-id=\"afb7da6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les questions \u00e0 se poser pour tout projet de vision<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4886cb elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"d4886cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Que veut-on (perce)voir ?\n<ul>\n<li>Je veux voir :\n<ul>\n<li>de loin<\/li>\n<li>de nuit<\/li>\n<li>\u00e0 travers des milieux diffusants (brouillard, neige, sous l\u2019eau\u2026)<\/li>\n<li>\u00e0 travers la mati\u00e8re<\/li>\n<li>rapidement<\/li>\n<li>dans tous les spectres (autre que le visible &gt; voir l\u2019invisible)<\/li>\n<li>\u00e0 tr\u00e8s haute fr\u00e9quence (voir \u00e0 10000 im\/s)<\/li>\n<li>voir avec un champ de vision tr\u00e8s large (pas loin) ou tr\u00e8s loin (champ de vision tr\u00e8s \u00e9troit)<\/li>\n<li>Tout le temps (ex : h24)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li>Que veut-on analyser ?\n<ul>\n<li>Ex : je veux reconnaitre la mati\u00e8re dont est fait ce que j\u2019observe<\/li>\n<li>DRI<\/li>\n<\/ul>\n<\/li>\n<li>Quelle temporalit\u00e9 ?\n<ul>\n<li>A quelle fr\u00e9quence je veux faire \u00e7a ?<\/li>\n<\/ul>\n<\/li>\n<li>Y\u2019a t\u2019il des contraintes particuli\u00e8res li\u00e9es au milieu d\u2019utilisation ?\n<ul>\n<li>Pression (par exemple dans l\u2019espace, en eau profonde\u2026)<\/li>\n<li>Temp\u00e9rature<\/li>\n<li>SWaP-c (Size, Weight, Power, Cost)<\/li>\n<li>Form factor :\n<ul>\n<li>Casque AR<\/li>\n<li>Cam\u00e9ra embarqu\u00e9e simple capteur<\/li>\n<li>Cam\u00e9ra embarqu\u00e9e multi-capteurs<\/li>\n<li>Design carte capteur<\/li>\n<li>Boule gyro<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li>Y-a-t&rsquo;il besoin de restituer l\u2019information ou l\u2019image \u00e0 l\u2019\u00eatre humain ?\n<ul>\n<li>Si oui, sous quelle forme (images, alerte&#8230;), sinon quelle action doit-on d\u00e9clencher (interfa\u00e7age syst\u00e8me) ?<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Concevoir un syst\u00e8me optronique Prototyper un syst\u00e8me de vision complet : calculateur + capteurs (vision, radar, lidar\u2026) Vous avez besoin de concevoir un syst\u00e8me embarqu\u00e9 complet qui r\u00e9sout votre probl\u00e9matique (d\u00e9tecter, reconna\u00eetre, identifier, d\u00e9clencher une action&#8230;) ? Nous d\u00e9risquons votre projet et concevons un syst\u00e8me incluant calculateur haute performance \u00e0 base de r\u00e9seaux de neurones [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-13591","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment identifier vos besoins pour votre projet optronique ?<\/title>\n<meta name=\"description\" content=\"Besoin d&#039;une solution sur mesure en vision avanc\u00e9e ? D\u00e9couvrez comment Nexvision peut r\u00e9pondre \u00e0 vos attentes. Cliquez ici !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nexvision.fr\/your-needs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment identifier vos besoins pour votre projet optronique ?\" \/>\n<meta property=\"og:description\" content=\"Besoin d&#039;une solution sur mesure en vision avanc\u00e9e ? D\u00e9couvrez comment Nexvision peut r\u00e9pondre \u00e0 vos attentes. Cliquez ici !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nexvision.fr\/your-needs\/\" \/>\n<meta property=\"og:site_name\" content=\"NEXVISION\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-26T13:53:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/03\/Ecosysteme-VPU_Mars2024-1024x724.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nexvision.fr\/your-needs\/\",\"url\":\"https:\/\/nexvision.fr\/your-needs\/\",\"name\":\"Comment identifier vos besoins pour votre projet optronique ?\",\"isPartOf\":{\"@id\":\"https:\/\/nexvision.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nexvision.fr\/your-needs\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nexvision.fr\/your-needs\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/03\/Ecosysteme-VPU_Mars2024-1024x724.png\",\"datePublished\":\"2024-04-17T15:44:29+00:00\",\"dateModified\":\"2024-09-26T13:53:17+00:00\",\"description\":\"Besoin d'une solution sur mesure en vision avanc\u00e9e ? D\u00e9couvrez comment Nexvision peut r\u00e9pondre \u00e0 vos attentes. Cliquez ici !\",\"breadcrumb\":{\"@id\":\"https:\/\/nexvision.fr\/your-needs\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nexvision.fr\/your-needs\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/nexvision.fr\/your-needs\/#primaryimage\",\"url\":\"https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/03\/Ecosysteme-VPU_Mars2024-1024x724.png\",\"contentUrl\":\"https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/03\/Ecosysteme-VPU_Mars2024-1024x724.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nexvision.fr\/your-needs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nexvision.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Votre besoin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nexvision.fr\/#website\",\"url\":\"https:\/\/nexvision.fr\/\",\"name\":\"NEXVISION\",\"description\":\"Vision solution : optronic system UV night SWIR LWIR Terahertz\",\"publisher\":{\"@id\":\"https:\/\/nexvision.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nexvision.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nexvision.fr\/#organization\",\"name\":\"NEXVISION\",\"url\":\"https:\/\/nexvision.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/nexvision.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nexvision.fr\/wp-content\/uploads\/2025\/10\/LogoNexvision696px.png\",\"contentUrl\":\"https:\/\/nexvision.fr\/wp-content\/uploads\/2025\/10\/LogoNexvision696px.png\",\"width\":696,\"height\":696,\"caption\":\"NEXVISION\"},\"image\":{\"@id\":\"https:\/\/nexvision.fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment identifier vos besoins pour votre projet optronique ?","description":"Besoin d'une solution sur mesure en vision avanc\u00e9e ? D\u00e9couvrez comment Nexvision peut r\u00e9pondre \u00e0 vos attentes. Cliquez ici !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nexvision.fr\/your-needs\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment identifier vos besoins pour votre projet optronique ?","og_description":"Besoin d'une solution sur mesure en vision avanc\u00e9e ? D\u00e9couvrez comment Nexvision peut r\u00e9pondre \u00e0 vos attentes. Cliquez ici !","og_url":"https:\/\/nexvision.fr\/your-needs\/","og_site_name":"NEXVISION","article_modified_time":"2024-09-26T13:53:17+00:00","og_image":[{"url":"https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/03\/Ecosysteme-VPU_Mars2024-1024x724.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nexvision.fr\/your-needs\/","url":"https:\/\/nexvision.fr\/your-needs\/","name":"Comment identifier vos besoins pour votre projet optronique ?","isPartOf":{"@id":"https:\/\/nexvision.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nexvision.fr\/your-needs\/#primaryimage"},"image":{"@id":"https:\/\/nexvision.fr\/your-needs\/#primaryimage"},"thumbnailUrl":"https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/03\/Ecosysteme-VPU_Mars2024-1024x724.png","datePublished":"2024-04-17T15:44:29+00:00","dateModified":"2024-09-26T13:53:17+00:00","description":"Besoin d'une solution sur mesure en vision avanc\u00e9e ? D\u00e9couvrez comment Nexvision peut r\u00e9pondre \u00e0 vos attentes. Cliquez ici !","breadcrumb":{"@id":"https:\/\/nexvision.fr\/your-needs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nexvision.fr\/your-needs\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nexvision.fr\/your-needs\/#primaryimage","url":"https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/03\/Ecosysteme-VPU_Mars2024-1024x724.png","contentUrl":"https:\/\/nexvision.fr\/wp-content\/uploads\/2024\/03\/Ecosysteme-VPU_Mars2024-1024x724.png"},{"@type":"BreadcrumbList","@id":"https:\/\/nexvision.fr\/your-needs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nexvision.fr\/"},{"@type":"ListItem","position":2,"name":"Votre besoin"}]},{"@type":"WebSite","@id":"https:\/\/nexvision.fr\/#website","url":"https:\/\/nexvision.fr\/","name":"NEXVISION","description":"Vision solution : optronic system UV night SWIR LWIR Terahertz","publisher":{"@id":"https:\/\/nexvision.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nexvision.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/nexvision.fr\/#organization","name":"NEXVISION","url":"https:\/\/nexvision.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nexvision.fr\/#\/schema\/logo\/image\/","url":"https:\/\/nexvision.fr\/wp-content\/uploads\/2025\/10\/LogoNexvision696px.png","contentUrl":"https:\/\/nexvision.fr\/wp-content\/uploads\/2025\/10\/LogoNexvision696px.png","width":696,"height":696,"caption":"NEXVISION"},"image":{"@id":"https:\/\/nexvision.fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/nexvision.fr\/fr\/wp-json\/wp\/v2\/pages\/13591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nexvision.fr\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nexvision.fr\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nexvision.fr\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nexvision.fr\/fr\/wp-json\/wp\/v2\/comments?post=13591"}],"version-history":[{"count":11,"href":"https:\/\/nexvision.fr\/fr\/wp-json\/wp\/v2\/pages\/13591\/revisions"}],"predecessor-version":[{"id":16631,"href":"https:\/\/nexvision.fr\/fr\/wp-json\/wp\/v2\/pages\/13591\/revisions\/16631"}],"wp:attachment":[{"href":"https:\/\/nexvision.fr\/fr\/wp-json\/wp\/v2\/media?parent=13591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}